{"id":5081,"date":"2025-04-13T10:12:49","date_gmt":"2025-04-13T10:12:49","guid":{"rendered":"https:\/\/sk8bright.andreiapeixoto.eu\/?post_type=product&#038;p=5081"},"modified":"2025-05-21T13:05:50","modified_gmt":"2025-05-21T13:05:50","slug":"tabua-longboard-star-versao-branco","status":"publish","type":"product","link":"https:\/\/sk8bright.andreiapeixoto.eu\/pt_pt\/produto\/tabua-longboard-star-versao-branco\/","title":{"rendered":"T\u00e1bua longboard &#8220;Star&#8221; vers\u00e3o branco"},"content":{"rendered":"<p><span style=\"color: #fff; font-family: century gothic;\">Composto por 9 camadas de madeira 100% canadiana, conhecida pela sua durabilidade e resist\u00eancia. Estas camadas de maple s\u0103o coladas com resina de epoxy para uma constru\u00e7\u0103o robusta e duradoura.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Composto por 9 camadas de madeira 100% canadiana, conhecida pela sua durabilidade e resist\u00eancia. Estas camadas de maple s\u0103o coladas com resina de epoxy para uma constru\u00e7\u0103o robusta e duradoura.<\/p>\n","protected":false},"featured_media":5087,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[101],"product_cat":[141],"product_tag":[],"class_list":["post-5081","product","type-product","status-publish","has-post-thumbnail","product_brand-sk8-bright","product_cat-tabua-longboard","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/sk8bright.andreiapeixoto.eu\/pt_pt\/wp-json\/wp\/v2\/product\/5081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sk8bright.andreiapeixoto.eu\/pt_pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sk8bright.andreiapeixoto.eu\/pt_pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sk8bright.andreiapeixoto.eu\/pt_pt\/wp-json\/wp\/v2\/comments?post=5081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sk8bright.andreiapeixoto.eu\/pt_pt\/wp-json\/wp\/v2\/media\/5087"}],"wp:attachment":[{"href":"https:\/\/sk8bright.andreiapeixoto.eu\/pt_pt\/wp-json\/wp\/v2\/media?parent=5081"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sk8bright.andreiapeixoto.eu\/pt_pt\/wp-json\/wp\/v2\/product_brand?post=5081"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sk8bright.andreiapeixoto.eu\/pt_pt\/wp-json\/wp\/v2\/product_cat?post=5081"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sk8bright.andreiapeixoto.eu\/pt_pt\/wp-json\/wp\/v2\/product_tag?post=5081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}